{"id":413,"count":1,"description":"","link":"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/","name":"Patient Engagement Practices","slug":"patient-engagement-practices","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patient Engagement Practices Archives - Imperial Clinical Research Services Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patient Engagement Practices Archives - Imperial Clinical Research Services Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/\" \/>\n<meta property=\"og:site_name\" content=\"Imperial Clinical Research Services Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/tag\\\/patient-engagement-practices\\\/\",\"url\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/tag\\\/patient-engagement-practices\\\/\",\"name\":\"Patient Engagement Practices Archives - Imperial Clinical Research Services Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/tag\\\/patient-engagement-practices\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/tag\\\/patient-engagement-practices\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patient Engagement Practices\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/\",\"name\":\"Imperial Clinical Research Services Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imperialcrs.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patient Engagement Practices Archives - Imperial Clinical Research Services Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Patient Engagement Practices Archives - Imperial Clinical Research Services Blog","og_url":"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/","og_site_name":"Imperial Clinical Research Services Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/","url":"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/","name":"Patient Engagement Practices Archives - Imperial Clinical Research Services Blog","isPartOf":{"@id":"https:\/\/www.imperialcrs.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imperialcrs.com\/blog\/tag\/patient-engagement-practices\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.imperialcrs.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Patient Engagement Practices"}]},{"@type":"WebSite","@id":"https:\/\/www.imperialcrs.com\/blog\/#website","url":"https:\/\/www.imperialcrs.com\/blog\/","name":"Imperial Clinical Research Services Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imperialcrs.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.imperialcrs.com\/blog\/wp-json\/wp\/v2\/tags\/413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imperialcrs.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.imperialcrs.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.imperialcrs.com\/blog\/wp-json\/wp\/v2\/posts?tags=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}